{"id":99999,"date":"2022-06-13T10:12:55","date_gmt":"2022-06-13T14:12:55","guid":{"rendered":"https:\/\/immigration.ca\/canada-unemployment-rate-hits-new-low-in-may-as-more-youth-and-women-get-full-time-jobs"},"modified":"2022-07-09T23:25:05","modified_gmt":"2022-07-10T03:25:05","slug":"canada-unemployment-rate-hits-new-low-in-may-as-more-youth-and-women-get-full-time-jobs","status":"publish","type":"post","link":"https:\/\/immigration.ca\/fr\/canada-unemployment-rate-hits-new-low-in-may-as-more-youth-and-women-get-full-time-jobs\/","title":{"rendered":"Le taux de ch\u00f4mage au Canada atteint son niveau le plus bas niveau en mai, car davantage de jeunes et de femmes obtiennent un emploi \u00e0 temps plein"},"content":{"rendered":"<p>Beaucoup plus de jeunes adultes et de femmes en \u00e2ge de travailler ont d\u00e9croch\u00e9 un emploi \u00e0 temps plein au Canada en mai, ce qui a fait grimper les chiffres de l&#8217;emploi dans le pays et a fait baisser le taux de ch\u00f4mage \u00e0 un nouveau niveau record.<\/p>\n<p>\u00ab Le Canada a cr\u00e9\u00e9 40 000 emplois en mai \u00bb, a tweet\u00e9 la ministre de l&rsquo;Emploi, Carla Qualtrough. \u00ab Notre taux d&#8217;emploi est maintenant de 5,1 pour cent, le taux le plus bas depuis 1976, lorsque ces donn\u00e9es ont \u00e9t\u00e9 recueillies pour la premi\u00e8re fois. Avec 117 % des emplois r\u00e9cup\u00e9r\u00e9s apr\u00e8s la pand\u00e9mie, l&rsquo;\u00e9conomie canadienne ne fait pas que se r\u00e9tablir, elle est en pleine croissance. \u00bb<\/p>\n<hr \/>\n<p><b>Si vous \u00eates un candidat \u00e0 la recherche d&rsquo;un emploi au Canada ou un employeur qui cherche \u00e0 recruter des talents \u00e9trangers, immigration.ca peut vous aider. Acc\u00e9dez \u00e0 notre expertise par le biais de nos entreprises de recrutement internes, <\/b><b>www.skilledworker.com<\/b><b> et de notre tout nouvel atout, <\/b><b>www.skilledworker.com<\/b><b>, \u00ab le leader du recrutement \u00e0 l&rsquo;\u00e9tranger \u00bb.<\/b><\/p>\n<hr \/>\n<p>Ce march\u00e9 du travail tr\u00e8s serr\u00e9 fait que de nombreux employeurs cherchent d\u00e9sesp\u00e9r\u00e9ment des travailleurs.<\/p>\n<p>Le rapport entre le nombre de ch\u00f4meurs et le nombre d&#8217;emplois vacants a atteint le niveau le plus bas jamais enregistr\u00e9, soit 1,2, en mars, selon Statistique Canada.<\/p>\n<p>\u00ab Une source potentielle d&rsquo;offre de main-d&rsquo;\u0153uvre est constitu\u00e9e par les personnes qui ne participent pas activement \u00e0 la population active, mais qui d\u00e9clarent vouloir travailler \u00bb, rapporte l&rsquo;organisme de services statistiques et d\u00e9mographiques. \u00ab En mai, on comptait 409 000 de ces travailleurs potentiels \u00bb.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<table cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"middle\"><b>Quels sont les faits saillants de l&rsquo;enqu\u00eate sur les forces de travail ?<\/b><\/p>\n<p><b>Taux de ch\u00f4mage (%) <\/b>5,1<\/p>\n<p><b>Taux d&#8217;emploi (%) <\/b>61,9<\/p>\n<p><b>Taux de participation \u00e0 la population active (%) <\/b>65,3<\/p>\n<p><b>Nombre de ch\u00f4meurs <\/b>1 057 800<\/p>\n<p><b>Nombre de travailleurs <\/b>19 640 300<\/p>\n<p><b>Taux de ch\u00f4mage des jeunes (15-24 ans) (%) <\/b>9,8<\/p>\n<p><b>Taux de ch\u00f4mage des hommes (plus de 25 ans) (%) <\/b>4,5<\/p>\n<p><b>Taux de ch\u00f4mage des femmes (plus de 25 ans) (%) <\/b>4,2<\/td>\n<td valign=\"middle\">4.2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><b>Source: Statistique Canada<\/b><\/p>\n<hr \/>\n<h3>Travailleurs \u00e9trangers temporaires et immigrants recherch\u00e9s par les employeurs canadiens pour combler des emplois<\/h3>\n<p>Les immigrants et les travailleurs \u00e9trangers temporaires sont d&rsquo;autres sources \u00e9videntes de travailleurs pour les employeurs canadiens.<\/p>\n<p>Les employeurs qui esp\u00e8rent embaucher un ressortissant \u00e9tranger peuvent se pr\u00e9valoir de ce talent et de cette main-d&rsquo;\u0153uvre internationale par le biais du Programme des travailleurs \u00e9trangers temporaires (PTET) et du Programme de mobilit\u00e9 internationale (PMI).<\/p>\n<p>Le Volet des talents mondiaux (VTM), qui fait partie du (PTET), peut, dans des situations normales de traitement, conduire \u00e0 l&rsquo;octroi de permis de travail canadiens et au traitement des demandes de visa en deux semaines.<\/p>\n<p>Les employeurs peuvent \u00e9galement faire venir des ressortissants \u00e9trangers pour pourvoir les postes disponibles par le biais du syst\u00e8me Entr\u00e9e Express, qui re\u00e7oit les demandes d&rsquo;immigration en ligne.<\/p>\n<hr \/>\n<p><b>En savoir plus<\/b><\/p>\n<p><a href=\"https:\/\/immigration.ca\/canada-crosses-milestone-of-welcoming-15000-afghan-refugees\">Le Canada franchit l&rsquo;\u00e9tape de l&rsquo;accueil de 15 000 r\u00e9fugi\u00e9s afghans<\/a><br \/>\n<a href=\"https:\/\/immigration.ca\/new-brunswick-launches-immigration-navigator-to-help-immigrants-find-jobs\">Le Nouveau-Brunswick lance le Navigateur en mati\u00e8re d&rsquo;immigration pour aider les immigrants \u00e0 trouver un emploi<\/a><br \/>\n<a href=\"https:\/\/immigration.ca\/british-columbia-draw-province-issues-more-than-140-canada-immigration-invitations\">Tirage au sort en Colombie-Britannique : La province \u00e9met plus de 140 invitations \u00e0 immigrer au Canada<\/a><\/p>\n<hr \/>\n<p>Les candidats qui r\u00e9pondent aux crit\u00e8res d&rsquo;admissibilit\u00e9 soumettent un profil en ligne appel\u00e9 d\u00e9claration d&rsquo;int\u00e9r\u00eat (EOI), dans le cadre de l&rsquo;un des trois programmes d&rsquo;immigration f\u00e9d\u00e9raux ou d&rsquo;un programme d&rsquo;immigration provincial participant, au bassin d&rsquo;entr\u00e9e express.<\/p>\n<p>Les profils des candidats sont ensuite class\u00e9s les uns par rapport aux autres en fonction d&rsquo;un syst\u00e8me de points appel\u00e9 le syst\u00e8me de classement global (SCG). Les candidats les mieux class\u00e9s sont pris en consid\u00e9ration pour l&rsquo;obtention d&rsquo;une invitation en vue de la r\u00e9sidence permanente. Ceux qui re\u00e7oivent cette invitation doivent rapidement soumettre une demande compl\u00e8te et payer les frais de traitement dans un d\u00e9lai de 90 jours.<\/p>\n<p>Il est certain que le Canada est optimiste en mati\u00e8re d&rsquo;immigration.<\/p>\n<p>Apr\u00e8s avoir atteint un niveau d&rsquo;immigration record, avec 405 970 nouveaux r\u00e9sidents permanents dans le pays l&rsquo;ann\u00e9e derni\u00e8re, le Canada a annonc\u00e9 qu&rsquo;il accueillerait 431 645 r\u00e9sidents permanents cette ann\u00e9e, 447 055 l&rsquo;ann\u00e9e prochaine et 451 000 en 2024.<\/p>\n<h3>Le nombre de personnes travaillant au Canada a augment\u00e9 en mai apr\u00e8s avoir marqu\u00e9 une pause en avril<\/h3>\n<p>Depuis lors, Ottawa s&rsquo;est \u00e9galement engag\u00e9 \u00e0 accepter un nombre illimit\u00e9 d&rsquo;Ukrainiens fuyant leur pays d\u00e9chir\u00e9 par la guerre pour trouver refuge au Canada. Au cours de ses deux premi\u00e8res semaines d&rsquo;existence seulement, la voie d&rsquo;acc\u00e8s \u00e0 <a href=\"https:\/\/immigration.ca\/how-to-apply-for-the-canada-ukraine-authorization-for-emergency-travel?nowprocket=1\">l&rsquo;Autorisation de voyage d&rsquo;urgence Canada-Ukraine<\/a> (AVUCU) a \u00e9t\u00e9 inond\u00e9e de plus de 112 000 demandes.<\/p>\n<p>Cette nouvelle voie permet aux Ukrainiens de rester au Canada jusqu&rsquo;\u00e0 trois ans et de b\u00e9n\u00e9ficier de <a href=\"https:\/\/immigration.ca\/fr\/visa-de-travail-canadien-travailler-au-canada\">permis de travail<\/a> et <a href=\"https:\/\/immigration.ca\/fr\/visa-etudiant-canada\">d&rsquo;\u00e9tudes<\/a> ouverts et gratuits.<\/p>\n<p>Aucun d&rsquo;entre eux ne devrait avoir de difficult\u00e9 \u00e0 trouver du travail au Canada.<\/p>\n<hr \/>\n<h3>Taux de ch\u00f4mage dans les provinces du Canada<\/h3>\n<table cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"middle\"><\/td>\n<td valign=\"middle\"><b>Jobs change in last month<\/b><\/td>\n<td valign=\"top\"><b>Taux de ch\u00f4mage (%)<\/b><\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>British Columbia<\/b><\/td>\n<td valign=\"middle\">5,100<\/td>\n<td valign=\"middle\">4.5<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>Alberta<\/b><\/td>\n<td valign=\"middle\">27,500<\/td>\n<td valign=\"middle\">5.3<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>Saskatchewan<\/b><\/td>\n<td valign=\"middle\">1,500<\/td>\n<td valign=\"middle\">4.8<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>Manitoba<\/b><\/td>\n<td valign=\"middle\">-500<\/td>\n<td valign=\"middle\">4.7<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>Ontario<\/b><\/td>\n<td valign=\"middle\">1,900<\/td>\n<td valign=\"middle\">5.5<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>Quebec<\/b><\/td>\n<td valign=\"middle\">5,100<\/td>\n<td valign=\"middle\">4.2<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>New Brunswick<\/b><\/td>\n<td valign=\"middle\">-3,900<\/td>\n<td valign=\"middle\">7.1<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>Nova Scotia<\/b><\/td>\n<td valign=\"middle\">-2,100<\/td>\n<td valign=\"middle\">6.7<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>Prince Edward Island<\/b><\/td>\n<td valign=\"middle\">1,100<\/td>\n<td valign=\"middle\">7.8<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>Newfoundland &amp; Labrador<\/b><\/td>\n<td valign=\"middle\">4,100<\/td>\n<td valign=\"middle\">10.0<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\"><b>CANADA<\/b><\/td>\n<td valign=\"middle\"><b>39,800<\/b><\/td>\n<td valign=\"middle\"><b>5.1<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><b>Source: Statistique Canada<\/b><\/p>\n<hr \/>\n<p>\u00ab La croissance de l&#8217;emploi a repris en mai apr\u00e8s avoir fait une pause en avril \u00bb, indique Statistique Canada dans sa plus r\u00e9cente Enqu\u00eate sur la population active.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>\u00ab L&#8217;emploi total a augment\u00e9 de 40 000, soit 0,2 pour cent, en mai, y compris une forte croissance du travail \u00e0 temps plein, en hausse de 135 000 emplois ou 0,9 pour cent. L&#8217;emploi \u00e0 temps partiel a diminu\u00e9 de 96 000, soit 2,6 pour cent. \u00bb<\/p>\n<p>Les femmes ont \u00e9t\u00e9 les grandes gagnantes en mai, \u00e0 l&rsquo;origine d&rsquo;une grande partie de la progression de l&#8217;emploi, alors que le tableau de l&#8217;emploi est rest\u00e9 pratiquement inchang\u00e9 pour les hommes.<\/p>\n<p>\u00ab Chez les femmes du groupe d&rsquo;\u00e2ge principal de 25 \u00e0 54 ans, l&#8217;emploi \u00e0 temps plein a augment\u00e9 de 63 000, soit une hausse de 1,2 pour cent, en mai, tandis que le travail \u00e0 temps partiel a diminu\u00e9 de 41 000, soit une baisse de quatre pour cent \u00bb, note Statistique Canada.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>\u00ab De m\u00eame, chez les jeunes femmes \u00e2g\u00e9es de 15 \u00e0 24 ans, les gains \u00e0 temps plein, en hausse de 53 000 emplois ou 10 pour cent, ont \u00e9t\u00e9 plus importants que les pertes \u00e0 temps partiel de 37 000, soit une baisse de 4,8 pour cent.\u00bb<\/p>\n<h3>Il y a maintenant plus d&#8217;emplois au Canada qu&rsquo;avant la pand\u00e9mie de COVID-19<\/h3>\n<p>Depuis le d\u00e9but de la troisi\u00e8me vague de la pand\u00e9mie de COVID-19, l&#8217;emploi total a augment\u00e9 de 1,1 million d&#8217;emplois, soit 5,7 %.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>En mai de cette ann\u00e9e, il y avait 497 000 emplois de plus qu&rsquo;avant le d\u00e9but de la pand\u00e9mie en f\u00e9vrier 2020.<\/p>\n<p>\u00ab L&rsquo;\u00e9conomie canadienne est sur une trajectoire de croissance claire et r\u00e9guli\u00e8re \u00bb, a tweet\u00e9 M. Qualtrough.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>\u00ab Depuis des mois, notre ch\u00f4mage est en baisse et notre cr\u00e9ation d&#8217;emplois est en hausse. Et maintenant, le Canada a la plus forte augmentation pr\u00e9vue du PIB au sein du G7. \u00bb<\/p>\n<p>Le moteur de la cr\u00e9ation d&#8217;emplois en mai a \u00e9t\u00e9 le secteur des services, o\u00f9 les emplois ont augment\u00e9 de 81 000 dans plusieurs industries.<\/p>\n<p>Le secteur de l&rsquo;h\u00e9bergement et des services de restauration a ajout\u00e9 20 000 emplois.<\/p>\n<p>Les services professionnels, scientifiques et techniques ont augment\u00e9 de 21 000 postes.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Le secteur de l&rsquo;\u00e9ducation a cr\u00e9\u00e9 24 000 emplois, tandis que le commerce de d\u00e9tail en a cr\u00e9\u00e9 34 000.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Des pertes ont toutefois \u00e9t\u00e9 enregistr\u00e9es dans le secteur du transport et de l&rsquo;entreposage, qui a perdu 25 000 emplois, ainsi que dans les secteurs de la finance, des assurances et de l&rsquo;immobilier, de la location et du cr\u00e9dit-bail, qui ont perdu 19 000 postes.<\/p>\n<p>Apr\u00e8s avoir atteint un plateau en avril, l&#8217;emploi global dans le secteur de la production de biens a diminu\u00e9 en mai de 41 000 postes.<\/p>\n<p>\u00c0 l&rsquo;\u00e9chelle du pays, Terre-Neuve-et-Labrador, l&rsquo;\u00cele-du-Prince-\u00c9douard et l&rsquo;Alberta ont ajout\u00e9 des emplois en mai, tandis que le Nouveau-Brunswick en a perdu.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>\u00ab \u00c0 Terre-Neuve-et-Labrador, l&#8217;emploi a augment\u00e9 de 4 100 postes en mai, soit la troisi\u00e8me hausse en quatre mois \u00bb, rapporte Statistique Canada. \u00ab L&rsquo;\u00cele-du-Prince-\u00c9douard a \u00e9galement connu une hausse de l&#8217;emploi en mai, soit 1 100 emplois. \u00bb<\/p>\n<p>L&rsquo;Alberta a ajout\u00e9 28 000 emplois ce mois-l\u00e0.<\/p>\n<p>\u00ab Le Nouveau-Brunswick a \u00e9t\u00e9 la seule province \u00e0 conna\u00eetre une baisse de l&#8217;emploi en mai, soit 3 900 emplois, ce qui a partiellement annul\u00e9 les gains enregistr\u00e9s en mars et en avril. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beaucoup plus de jeunes adultes et de femmes en \u00e2ge de travailler ont d\u00e9croch\u00e9 un emploi \u00e0 temps plein au Canada en mai, ce qui a fait grimper les chiffres de l&#8217;emploi dans le pays et a fait baisser le taux de ch\u00f4mage \u00e0 un nouveau niveau record. \u00ab Le Canada a cr\u00e9\u00e9 40 000&hellip;<\/p>\n","protected":false},"author":16,"featured_media":99992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-99999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","description-off"],"acf":[],"_links":{"self":[{"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/posts\/99999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/comments?post=99999"}],"version-history":[{"count":0,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/posts\/99999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/media\/99992"}],"wp:attachment":[{"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/media?parent=99999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/categories?post=99999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/tags?post=99999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}