{"id":5011,"date":"2016-06-20T18:19:02","date_gmt":"2016-06-20T18:19:02","guid":{"rendered":"https:\/\/immigrationca.staging.wpengine.com\/fr\/?p=5011"},"modified":"2016-06-20T18:19:02","modified_gmt":"2016-06-20T18:19:02","slug":"changements-aux-regles-de-citoyennete-pourraient-dissuader-les-immigrants-qualifies","status":"publish","type":"post","link":"https:\/\/immigration.ca\/fr\/changements-aux-regles-de-citoyennete-pourraient-dissuader-les-immigrants-qualifies\/","title":{"rendered":"Changements aux r\u00e8gles de citoyennet\u00e9 pourraient dissuader les immigrants qualifi\u00e9s"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Les critiques se disent inquiets au sujet des r\u00e9formes du droit de citoyennet\u00e9 du Canada, disant que les changements rendront l&rsquo;obtention de la citoyennet\u00e9 canadienne plus difficile pour les nouveaux arrivants et d\u00e9valuera la citoyennet\u00e9 des Canadiens vivant \u00e0 l&rsquo;\u00e9tranger.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">La loi renfor\u00e7ant la citoyennet\u00e9 canadienne fut pr\u00e9sent\u00e9e par le gouvernement conservateur au Parlement en d\u00e9but d&rsquo;ann\u00e9e, et vise \u00e0 prolonger le temps requis pour se qualifier \u00e0 la citoyennet\u00e9 apr\u00e8s l&rsquo;obtention du statut de r\u00e9sident permanent.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Alors que les repr\u00e9sentants du gouvernement, dont le ministre de l&rsquo;Immigration Chris Alexander, vantent les changements comme un moyen d&rsquo;am\u00e9liorer le syst\u00e8me de citoyennet\u00e9 et faire en sorte que \u00ables gens qui deviennent citoyens aient vraiment v\u00e9cu ici,\u00a0\u00bb les critiques craignent que les changements ne d\u00e9couragent les immigrants de demander le statut de citoyen et, contrairement aux objectifs d\u00e9clar\u00e9s du gouvernement, n&rsquo;affaiblissent leur attachement et leur loyaut\u00e9 envers le Canada.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Les immigrants re\u00e7us ont acc\u00e8s aux services sociaux du Canada, mais ils ne peuvent pas voter et ne sont pas impos\u00e9s au m\u00eame taux. Il s&rsquo;agit de deux facteurs qui pourraient affaiblir \u00e0 la fois leur attachement au Canada, ainsi que l&rsquo;investissement du Canada en eux. Dans le nouveau march\u00e9 mondial, un sentiment de loyaut\u00e9 envers leur pays adoptif est imp\u00e9ratif pour que les travailleurs qualifi\u00e9s s&rsquo;\u00e9tablissent \u00e0 long terme, soutiennent le professeur d&rsquo;\u00e9conomie Don Devoretz et le pr\u00e9sident de la Fondation Asie Pacifique du Canada Yuen Pau Woo dans un article r\u00e9cent du Toronto Star.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Devoretz et Woo disent que les politiques fond\u00e9es sur un sentiment de d\u00e9pit &#8211; l&rsquo;id\u00e9e que certains nouveaux arrivants prennent pour acquis la citoyennet\u00e9 canadienne &#8211; pourraient plaire \u00e0 certains groupes au Canada, mais pourraient dissuader les travailleurs qualifi\u00e9s que les politiques d&rsquo;immigration canadiennes cherchent \u00e0 recruter. Cela est particuli\u00e8rement vrai des jeunes travailleurs instruits, qui sont les plus susceptibles de travailler \u00e0 l&rsquo;\u00e9tranger pour de longues p\u00e9riodes de temps.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">La r\u00e9ponse, disent-ils, n&rsquo;est pas de rendre l&rsquo;obtention de la citoyennet\u00e9 plus difficile, mais plut\u00f4t de limiter l&rsquo;acc\u00e8s aux b\u00e9n\u00e9fices et services sociaux pour ceux qui d\u00e9cident de vivre \u00e0 l&rsquo;ext\u00e9rieur du pays. Une politique d&rsquo;immigration qui est con\u00e7u pour attirer des travailleurs qualifi\u00e9s au Canada devrait \u00e9galement se pr\u00e9occuper de la r\u00e9tention \u00e0 long-terme de ces immigrants.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Sources: Toronto Star;\u00a0www.cbc.ca<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les critiques se disent inquiets au sujet des r\u00e9formes du droit de citoyennet\u00e9 du Canada, disant que les changements rendront l&rsquo;obtention de la citoyennet\u00e9 canadienne plus difficile pour les nouveaux arrivants et d\u00e9valuera la citoyennet\u00e9 des Canadiens vivant \u00e0 l&rsquo;\u00e9tranger. La loi renfor\u00e7ant la citoyennet\u00e9 canadienne fut pr\u00e9sent\u00e9e par le gouvernement conservateur au Parlement en&hellip;<\/p>\n","protected":false},"author":498,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-5011","post","type-post","status-publish","format-standard","hentry","description-off"],"acf":[],"_links":{"self":[{"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/posts\/5011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/users\/498"}],"replies":[{"embeddable":true,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/comments?post=5011"}],"version-history":[{"count":0,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/posts\/5011\/revisions"}],"wp:attachment":[{"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/media?parent=5011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/categories?post=5011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immigration.ca\/fr\/wp-json\/wp\/v2\/tags?post=5011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}